{"id":393,"date":"2023-04-11T13:43:48","date_gmt":"2023-04-11T13:43:48","guid":{"rendered":"https:\/\/cprprovenances.eu\/?post_type=tribe_events&#038;p=393"},"modified":"2023-04-11T13:43:48","modified_gmt":"2023-04-11T13:43:48","slug":"evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles","status":"publish","type":"tribe_events","link":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\/","title":{"rendered":"[\u00e9v\u00e9nement] Collectionner les traces et tracer les collections dans les aires hispaniques et hispano-am\u00e9ricaines des XIX-XXIe si\u00e8cles"},"content":{"rendered":"<p>Le Laboratoire Junior\u00a0<a class=\"external\" href=\"https:\/\/latrace.hypotheses.org\/\">La Trace<\/a>\u00a0(ED 122, CREC UR 2292,\u00a0<a class=\"external\" href=\"http:\/\/www.univ-paris3.fr\/collectionner-les-traces-et-tracer-les-collections-780492.kjsp\">Universit\u00e9 Sorbonne Nouvelle<\/a>), parall\u00e8lement \u00e0 son s\u00e9minaire mensuel dont le premier a eu lieu en janvier 2022, organise un colloque international. Le\u00a0<dfn title=\"Bachelor Universitaire de Technologie\">but<\/dfn>\u00a0\u00e9tant de\u00a0prolonger la r\u00e9flexion sur la trace en sciences humaines,\u00a0sous la forme d\u2019une rencontre plurielle sur deux jours, les 13 et 14 avril 2023.<\/p>\n<p>Le concept qui a \u00e9t\u00e9 retenu est celui des collections dans les \u00e9tudes hispaniques et hispano-am\u00e9ricaines, depuis la perspective des \u00e9tudes culturelles,\u00a0de l\u2019histoire de l\u2019art, de l\u2019histoire, de la philosophie, des arts plastiques, de la sociologie, de l\u2019anthropologie ou encore des sciences politiques, au cours des trois derniers si\u00e8cles (XIX<sup>e<\/sup>\u00a0-XXI<sup>e<\/sup>).<\/p>\n<p>Lors de ces deux jours, seront r\u00e9unis des\u00a0chercheurs, des artistes\u00a0parmi lesquels\u00a0un graffeur\u00a0madril\u00e8ne,\u00a0une cin\u00e9aste\u00a0argentine,\u00a0une dessinatrice\u00a0franco-uruguayenne et\u00a0un photographe\u00a0fran\u00e7ais. Un vernissage des expositions est pr\u00e9vu le jeudi 13 avril \u00e0 17h30 \u00e0 la Maison de la Recherche \u00e9galement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Laboratoire Junior\u00a0La Trace\u00a0(ED 122, CREC UR 2292,\u00a0Universit\u00e9 Sorbonne Nouvelle), parall\u00e8lement \u00e0 son s\u00e9minaire mensuel dont le premier a eu lieu en janvier 2022, organise un colloque international. Le\u00a0but\u00a0\u00e9tant de\u00a0prolonger [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[14],"tribe_events_cat":[4],"class_list":["post-393","tribe_events","type-tribe_events","status-publish","hentry","tag-collections","tribe_events_cat-evenement","cat_evenement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[\u00e9v\u00e9nement] Collectionner les traces et tracer les collections dans les aires hispaniques et hispano-am\u00e9ricaines des XIX-XXIe si\u00e8cles - CPRProvenances<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[\u00e9v\u00e9nement] Collectionner les traces et tracer les collections dans les aires hispaniques et hispano-am\u00e9ricaines des XIX-XXIe si\u00e8cles - CPRProvenances\" \/>\n<meta property=\"og:description\" content=\"Le Laboratoire Junior\u00a0La Trace\u00a0(ED 122, CREC UR 2292,\u00a0Universit\u00e9 Sorbonne Nouvelle), parall\u00e8lement \u00e0 son s\u00e9minaire mensuel dont le premier a eu lieu en janvier 2022, organise un colloque international. Le\u00a0but\u00a0\u00e9tant de\u00a0prolonger [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\/\" \/>\n<meta property=\"og:site_name\" content=\"CPRProvenances\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/event\\\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\\\/\",\"url\":\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/event\\\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\\\/\",\"name\":\"[\u00e9v\u00e9nement] Collectionner les traces et tracer les collections dans les aires hispaniques et hispano-am\u00e9ricaines des XIX-XXIe si\u00e8cles - CPRProvenances\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cprprovenances.eu\\\/#website\"},\"datePublished\":\"2023-04-11T13:43:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/event\\\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/event\\\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/event\\\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cprprovenances.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/actualites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"[\u00e9v\u00e9nement] Collectionner les traces et tracer les collections dans les aires hispaniques et hispano-am\u00e9ricaines des XIX-XXIe si\u00e8cles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cprprovenances.eu\\\/#website\",\"url\":\"https:\\\/\\\/cprprovenances.eu\\\/\",\"name\":\"CPRProvenances\",\"description\":\"Le blog du Collectif Pluridisciplinaire de Recherche de Provenances\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cprprovenances.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[\u00e9v\u00e9nement] Collectionner les traces et tracer les collections dans les aires hispaniques et hispano-am\u00e9ricaines des XIX-XXIe si\u00e8cles - CPRProvenances","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\/","og_locale":"fr_FR","og_type":"article","og_title":"[\u00e9v\u00e9nement] Collectionner les traces et tracer les collections dans les aires hispaniques et hispano-am\u00e9ricaines des XIX-XXIe si\u00e8cles - CPRProvenances","og_description":"Le Laboratoire Junior\u00a0La Trace\u00a0(ED 122, CREC UR 2292,\u00a0Universit\u00e9 Sorbonne Nouvelle), parall\u00e8lement \u00e0 son s\u00e9minaire mensuel dont le premier a eu lieu en janvier 2022, organise un colloque international. Le\u00a0but\u00a0\u00e9tant de\u00a0prolonger [&hellip;]","og_url":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\/","og_site_name":"CPRProvenances","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\/","url":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\/","name":"[\u00e9v\u00e9nement] Collectionner les traces et tracer les collections dans les aires hispaniques et hispano-am\u00e9ricaines des XIX-XXIe si\u00e8cles - CPRProvenances","isPartOf":{"@id":"https:\/\/cprprovenances.eu\/#website"},"datePublished":"2023-04-11T13:43:48+00:00","breadcrumb":{"@id":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cprprovenances.eu\/index.php\/event\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-collectionner-les-traces-et-tracer-les-collections-dans-les-aires-hispaniques-et-hispano-americaines-des-xix-xxie-siecles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cprprovenances.eu\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/cprprovenances.eu\/index.php\/actualites\/"},{"@type":"ListItem","position":3,"name":"[\u00e9v\u00e9nement] Collectionner les traces et tracer les collections dans les aires hispaniques et hispano-am\u00e9ricaines des XIX-XXIe si\u00e8cles"}]},{"@type":"WebSite","@id":"https:\/\/cprprovenances.eu\/#website","url":"https:\/\/cprprovenances.eu\/","name":"CPRProvenances","description":"Le blog du Collectif Pluridisciplinaire de Recherche de Provenances","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cprprovenances.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tribe_events\/393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tribe_events\/393\/revisions"}],"predecessor-version":[{"id":402,"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tribe_events\/393\/revisions\/402"}],"wp:attachment":[{"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/media?parent=393"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tags?post=393"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}