{"id":388,"date":"2023-04-11T13:32:51","date_gmt":"2023-04-11T13:32:51","guid":{"rendered":"https:\/\/cprprovenances.eu\/?post_type=tribe_events&#038;p=388"},"modified":"2023-04-11T13:44:16","modified_gmt":"2023-04-11T13:44:16","slug":"evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions","status":"publish","type":"tribe_events","link":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\/","title":{"rendered":"[\u00e9v\u00e9nement] Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions."},"content":{"rendered":"<p>Les Minno sont ravi.es de vous pr\u00e9senter leur troisi\u00e8me conf\u00e9rence de l&rsquo;ann\u00e9e : Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions.<\/p>\n<p>Nous vous proposons un panorama des enjeux actuels et des derni\u00e8res innovations concernant les institutions culturelles et mus\u00e9ales :<\/p>\n<p>&#8211; Quelle place donner au num\u00e9rique dans nos expositions ? Comment stimuler les sens et am\u00e9liorer l\u2019exp\u00e9rience de visite ?<\/p>\n<p>&#8211; Que faire des \u0153uvres pill\u00e9es pendant la colonisation, des \u0153uvres spoli\u00e9es par l\u2019Allemagne nazie ? Dans quelles mesures les \u00e9tablissements culturels transmettent une m\u00e9moire et s\u2019engagent sur de nouvelles pr\u00e9occupations sociales et environnementales ?<\/p>\n<p>&#8211; Comment faire des mus\u00e9es un lieu inclusif ? Quelles possibilit\u00e9s de m\u00e9diation aupr\u00e8s d\u2019un public malvoyant par exemple ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Minno sont ravi.es de vous pr\u00e9senter leur troisi\u00e8me conf\u00e9rence de l&rsquo;ann\u00e9e : Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions. Nous vous proposons [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[11,8,9,10],"tribe_events_cat":[4],"class_list":["post-388","tribe_events","type-tribe_events","status-publish","hentry","tag-colonisation","tag-evenement","tag-seconde-guerre-mondiale","tag-spoliations","tribe_events_cat-evenement","cat_evenement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[\u00e9v\u00e9nement] Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions. - CPRProvenances<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[\u00e9v\u00e9nement] Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions. - CPRProvenances\" \/>\n<meta property=\"og:description\" content=\"Les Minno sont ravi.es de vous pr\u00e9senter leur troisi\u00e8me conf\u00e9rence de l&rsquo;ann\u00e9e : Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions. Nous vous proposons [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\/\" \/>\n<meta property=\"og:site_name\" content=\"CPRProvenances\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-11T13:44:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/event\\\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\\\/\",\"url\":\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/event\\\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\\\/\",\"name\":\"[\u00e9v\u00e9nement] Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions. - CPRProvenances\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cprprovenances.eu\\\/#website\"},\"datePublished\":\"2023-04-11T13:32:51+00:00\",\"dateModified\":\"2023-04-11T13:44:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/event\\\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/event\\\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/event\\\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cprprovenances.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\\\/\\\/cprprovenances.eu\\\/index.php\\\/actualites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"[\u00e9v\u00e9nement] Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cprprovenances.eu\\\/#website\",\"url\":\"https:\\\/\\\/cprprovenances.eu\\\/\",\"name\":\"CPRProvenances\",\"description\":\"Le blog du Collectif Pluridisciplinaire de Recherche de Provenances\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cprprovenances.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[\u00e9v\u00e9nement] Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions. - CPRProvenances","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\/","og_locale":"fr_FR","og_type":"article","og_title":"[\u00e9v\u00e9nement] Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions. - CPRProvenances","og_description":"Les Minno sont ravi.es de vous pr\u00e9senter leur troisi\u00e8me conf\u00e9rence de l&rsquo;ann\u00e9e : Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions. Nous vous proposons [&hellip;]","og_url":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\/","og_site_name":"CPRProvenances","article_modified_time":"2023-04-11T13:44:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\/","url":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\/","name":"[\u00e9v\u00e9nement] Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions. - CPRProvenances","isPartOf":{"@id":"https:\/\/cprprovenances.eu\/#website"},"datePublished":"2023-04-11T13:32:51+00:00","dateModified":"2023-04-11T13:44:16+00:00","breadcrumb":{"@id":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cprprovenances.eu\/index.php\/event\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cprprovenances.eu\/index.php\/event\/evenement-le-renouvellement-du-role-des-musees-entre-inclusivite-decolonisation-et-esthetisme-des-expositions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cprprovenances.eu\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/cprprovenances.eu\/index.php\/actualites\/"},{"@type":"ListItem","position":3,"name":"[\u00e9v\u00e9nement] Le renouvellement du r\u00f4le des mus\u00e9es : entre inclusivit\u00e9, d\u00e9colonisation et esth\u00e9tisme des expositions."}]},{"@type":"WebSite","@id":"https:\/\/cprprovenances.eu\/#website","url":"https:\/\/cprprovenances.eu\/","name":"CPRProvenances","description":"Le blog du Collectif Pluridisciplinaire de Recherche de Provenances","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cprprovenances.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tribe_events\/388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tribe_events\/388\/revisions"}],"predecessor-version":[{"id":391,"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tribe_events\/388\/revisions\/391"}],"wp:attachment":[{"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/media?parent=388"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tags?post=388"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/cprprovenances.eu\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}